{"id":3361,"date":"2023-05-27T16:36:09","date_gmt":"2023-05-27T14:36:09","guid":{"rendered":"https:\/\/creativ-ariane.fr\/?p=3361"},"modified":"2023-05-27T16:41:01","modified_gmt":"2023-05-27T14:41:01","slug":"effets-matiere","status":"publish","type":"post","link":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/","title":{"rendered":"Effets &#038; mati\u00e8re"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans une pr\u00e9c\u00e9dente vid\u00e9o, nous avons appris a utiliser des mati\u00e8res, des mat\u00e9riaux pour amener des effets dans une aquarelle. Je propose la r\u00e9alisation d&rsquo;un paysage abstrait de mer, vagues et plage. Vous y utiliserez  de la p\u00e2te granuleuse, du ruban de masquage, une carte plastique, du gel de masquage, une \u00e9ponge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette composition part d&rsquo;un paysage imaginaire o\u00f9 m&rsquo;on se trouve au bord de la mer avec les vagues qui d\u00e9ferlent et on regarde le lointain. Il apparait du relief de la quasi 3D dans le r\u00e9sultat assez int\u00e9ressant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le tout est expliqu\u00e9 \u00e9tape par \u00e9tape comme toujours. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je vous souhaite une belle f\u00eate de pentec\u00f4te. Alors Belle d\u00e9couverte de ces effets !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ariane<\/p>\n\n\n\n<div class=\"alignfull wp-block-ugb-video-popup ugb-video-popup ugb-e661b32 ugb-video-popup--v3 ugb-main-block\"><style>.ugb-e661b32 .ugb-video-popup__wrapper{height:600px !important;background-color:#eeeeee;background-image:url(https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/effets-pour-aquarelle-abstraite.jpg)}.ugb-e661b32 .ugb-video-popup__play-button svg{fill:#eeeeee !important;height:115px;width:115px}.ugb-e661b32 .ugb-video-popup__wrapper:before{background-color:#eeeeee;opacity:0.1}.ugb-e661b32 .ugb-video-popup__wrapper:hover:before{opacity:0.4}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><div class=\"ugb-video-popup__wrapper ugb--shadow-0 ugb--has-background-overlay\" data-video=\"DfewErgf7cc\"><button class=\"ugb-video-popup__overlay\" aria-label=\"Play\"><span class=\"ugb-video-popup__play-button\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 40 40\" class=\"ugb-play-button-cirle\" width=\"50\" height=\"50\"><path d=\"M16 29l12-9-12-9v18zm4-29C8.95 0 0 8.95 0 20s8.95 20 20 20 20-8.95 20-20S31.05 0 20 0zm0 36c-8.82 0-16-7.18-16-16S11.18 4 20 4s16 7.18 16 16-7.18 16-16 16z\"><\/path><\/svg><\/span><\/button><\/div><\/div><\/div><\/div>\n\n\n\n<h1 class=\"wp-block-heading\" data-block-type=\"core\">R\u00e9alisation de l&rsquo;aquarelle de paysage<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">1. <strong>Mat\u00e9riel utilis\u00e9<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\" data-block-type=\"core\">\n<li data-block-type=\"core\">Papier Canson Heritage 300 gr grain torchon 31 x 41 cm <\/li>\n\n\n\n<li data-block-type=\"core\">Aquarelles W&amp;N bleus, verts, violet, jaune, ocre <\/li>\n\n\n\n<li data-block-type=\"core\">AQUA P\u00e2te \u00e0 modeler granuleuse de Schmincke <\/li>\n\n\n\n<li data-block-type=\"core\">Drawing gum P\u00e9b\u00e9o <\/li>\n\n\n\n<li data-block-type=\"core\">Ruban blanc de masquage <\/li>\n\n\n\n<li data-block-type=\"core\">Divers pinceaux dont un \u00e0 lavis Escoda<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">2. Pr\u00e9paration des effets aquarelle<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Je place sur le paier de la pate granuleuse au centre pour marquer les vagues, du ruban de masquage au fond du paysage rn mignr horizontale en d\u00e9chirant le papier, du gel de masquage par par l\u00e0 au pinceau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Revoyez le tuto sur ces effets <strong><a href=\"https:\/\/creativ-ariane.fr\/index.php\/2023\/04\/01\/realiser-4-effets-pour-aquarelle-abstraite\/\">ici.<\/a><\/strong> <\/p>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-36b4689\" data-block-id=\"36b4689\"><figure class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-3376\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/preparation-effets.jpg\" width=\"800\" height=\"500\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/preparation-effets.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/preparation-effets-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/preparation-effets-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">2. Les \u00e9tapes de peinture<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le ciel au lavis<\/strong> : avec le gros pinceau, j&rsquo;humidifie et je place des couleurs de violet, bleu et jaune qui se fondent pour faire le ciel.<\/p>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-5299d9c\" data-block-id=\"5299d9c\"><figure class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-3366\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/lavis-fond-du-ciel.jpg\" width=\"800\" height=\"500\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/lavis-fond-du-ciel.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/lavis-fond-du-ciel-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/lavis-fond-du-ciel-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La mer au lavis <\/strong>: de la m\u00eame fa\u00e7on je r\u00e9alise le fond clair de la mer en utilisant de verts et du jaune au centre comme le reflet de celui du ciel.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-mer-lavis.jpg\" alt=\"\" class=\"wp-image-3372\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-mer-lavis.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-mer-lavis-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-mer-lavis-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La plage :<\/strong> j&rsquo;utilise des jaunes et ocres. En mettant des ocres plus fonc\u00e9s et du gris je tamponne ensuite ces couleurs avec une \u00e9ponge naturelle et je reporte ainsi des effets sur les zones proches.<\/p>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-877013b\" data-block-id=\"877013b\"><figure class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-3373\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-plage-et-eponge.jpg\" width=\"800\" height=\"500\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-plage-et-eponge.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-plage-et-eponge-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-plage-et-eponge-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arri\u00e8re plan : <\/strong><br>Je prend un pinceau fin et je place deux zones plus fonc\u00e9es sur la ligne d&rsquo;horizon, les couleurs diffusent car le papier est encore l\u00e9g\u00e8rement humide. J&rsquo; enl\u00e8ve ensuite quelques \u00e9l\u00e9ments de masquage, ruban et gel (en le frottant), et je peint d\u00e9licatement ces parties en en laissant certaines bien blanches.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\" data-block-type=\"core\">\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3365\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/enlever-masquage.jpg\" alt=\"\" class=\"wp-image-3365\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/enlever-masquage.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/enlever-masquage-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/enlever-masquage-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3368\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-arriere-plan-debut.jpg\" alt=\"\" class=\"wp-image-3368\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-arriere-plan-debut.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-arriere-plan-debut-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-arriere-plan-debut-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">On peut ensuite ajouter de la peinture sur la p\u00e2te granuleuse en en mettant de la plus fonc\u00e9e dans les creux.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\" data-block-type=\"core\">\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3375\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-sur-la-pate.jpg\" alt=\"\" class=\"wp-image-3375\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-sur-la-pate.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-sur-la-pate-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-sur-la-pate-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3379\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-des-vagues-sur-la-pate.jpg\" alt=\"\" class=\"wp-image-3379\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-des-vagues-sur-la-pate.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-des-vagues-sur-la-pate-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-des-vagues-sur-la-pate-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>V\u00e9g\u00e9tation \u00e0 droite :<\/strong> Effet \u00e0 r\u00e9aliser avec la carte plastique. Je met de la couleur pure du tube de violet sur le bord de la carte, que j&rsquo;\u00e9tale de haut en bas, en grattant le papier.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\" data-block-type=\"core\">\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3370\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte.jpg\" alt=\"\" class=\"wp-image-3370\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3369\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte-2.jpg\" alt=\"\" class=\"wp-image-3369\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte-2.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte-2-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-avec-la-carte-2-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Avec de l&rsquo;eau claire, je peux \u00e9taler cette peinture par endroit et \u00e9claircir, ajouter des verts gris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je peux faire de m\u00eame sur une zone en bas \u00e0 gauche. Et j&rsquo;apporte plus de couleurs sur le sable, apr\u00e8s avoir enlev\u00e9 encore des morceaux de ruban et le gel de masquage.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-etalement.jpg\" alt=\"\" class=\"wp-image-3371\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-etalement.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-etalement-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-etalement-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-renfort.jpg\" alt=\"\" class=\"wp-image-3374\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-renfort.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-renfort-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/peinture-renfort-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Renfort de couleurs : j<\/strong>e fais des petits traits horizontaux sur la mer, et je renforce la peinture de l&rsquo;arri\u00e8re plan pour donner plus de relief.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\" data-block-type=\"core\">\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3363\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-sur-la-mer.jpg\" alt=\"\" class=\"wp-image-3363\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-sur-la-mer.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-sur-la-mer-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-sur-la-mer-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" data-id=\"3362\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg\" alt=\"\" class=\"wp-image-3362\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-300x188.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Voici l&rsquo;aquarelle termin\u00e9e. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"594\" src=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/effets-pour-aquarelle-abstraite.jpg\" alt=\"\" class=\"wp-image-3364\" srcset=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/effets-pour-aquarelle-abstraite.jpg 800w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/effets-pour-aquarelle-abstraite-300x223.jpg 300w, https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/effets-pour-aquarelle-abstraite-768x570.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">D&rsquo;autres vid\u00e9os que vous aimerez : <\/h2>\n\n\n\n<ul class=\"wp-block-list\" data-block-type=\"core\">\n<li data-block-type=\"core\"><a href=\"https:\/\/creativ-ariane.fr\/index.php\/2022\/03\/28\/melange-de-couleurs\/\">Le m\u00e9lange des couleurs<\/a><\/li>\n\n\n\n<li data-block-type=\"core\"><a href=\"https:\/\/creativ-ariane.fr\/index.php\/2021\/12\/05\/quest-ce-que-la-granulation-en-aquarelle\/\">La granulation<\/a>, paysage d&rsquo;hiver<\/li>\n\n\n\n<li data-block-type=\"core\"><a href=\"https:\/\/creativ-ariane.fr\/index.php\/2023\/01\/19\/peindre-un-paysage-semi-abstrait\/\">Peinture semi abstraite<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans une pr\u00e9c\u00e9dente vid\u00e9o, nous avons appris a utiliser des mati\u00e8res, des mat\u00e9riaux pour amener des effets dans une aquarelle. Je propose la r\u00e9alisation d&rsquo;un paysage abstrait de mer, vagues et plage. Vous y utiliserez de la p\u00e2te granuleuse, du ruban de masquage, une carte plastique, du gel de masquage, une \u00e9ponge. Cette composition part d&rsquo;un paysage imaginaire o\u00f9 m&rsquo;on se trouve au bord de la mer avec les vagues qui d\u00e9ferlent et on regarde le lointain. Il apparait du relief de la quasi 3D dans le r\u00e9sultat assez int\u00e9ressant. Le tout est expliqu\u00e9 \u00e9tape par \u00e9tape comme toujours. Je vous souhaite une belle f\u00eate de pentec\u00f4te. Alors Belle d\u00e9couverte de ces effets ! Ariane R\u00e9alisation de l&rsquo;aquarelle de paysage 1. Mat\u00e9riel utilis\u00e9 2. Pr\u00e9paration des effets aquarelle Je place sur le paier de la pate granuleuse au centre pour marquer les vagues, du ruban de masquage au fond du paysage rn mignr horizontale en d\u00e9chirant le papier, du gel de masquage par par l\u00e0 au pinceau. Revoyez le tuto sur ces effets ici. 2. Les \u00e9tapes de peinture Le ciel au lavis : avec le gros pinceau, j&rsquo;humidifie et je place des couleurs de violet, bleu et jaune qui se fondent pour faire le ciel. La mer au lavis : de la m\u00eame fa\u00e7on je r\u00e9alise le fond clair de la mer en utilisant de verts et du jaune au centre comme le reflet de celui du ciel. La plage : j&rsquo;utilise des jaunes et ocres. En mettant des ocres plus fonc\u00e9s et du gris je tamponne ensuite ces couleurs avec une \u00e9ponge naturelle et je reporte ainsi des effets sur les zones proches. Arri\u00e8re plan : Je prend un pinceau fin et je place deux zones plus fonc\u00e9es sur la ligne d&rsquo;horizon, les couleurs diffusent car le papier est encore l\u00e9g\u00e8rement humide. J&rsquo; enl\u00e8ve ensuite quelques \u00e9l\u00e9ments de masquage, ruban et gel (en le frottant), et je peint d\u00e9licatement ces parties en en laissant certaines bien blanches. On peut ensuite ajouter de la peinture sur la p\u00e2te granuleuse en en mettant de la plus fonc\u00e9e dans les creux. V\u00e9g\u00e9tation \u00e0 droite : Effet \u00e0 r\u00e9aliser avec la carte plastique. Je met de la couleur pure du tube de violet sur le bord de la carte, que j&rsquo;\u00e9tale de haut en bas, en grattant le papier. Avec de l&rsquo;eau claire, je peux \u00e9taler cette peinture par endroit et \u00e9claircir, ajouter des verts gris. Je peux faire de m\u00eame sur une zone en bas \u00e0 gauche. Et j&rsquo;apporte plus de couleurs sur le sable, apr\u00e8s avoir enlev\u00e9 encore des morceaux de ruban et le gel de masquage. Renfort de couleurs : je fais des petits traits horizontaux sur la mer, et je renforce la peinture de l&rsquo;arri\u00e8re plan pour donner plus de relief. Voici l&rsquo;aquarelle termin\u00e9e. D&rsquo;autres vid\u00e9os que vous aimerez :<\/p>\n","protected":false},"author":1,"featured_media":3362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[95,80],"class_list":["post-3361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquarelle","tag-abstrait","tag-effets"],"featured_image_urls_v2":{"full":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg",800,500,false],"thumbnail":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-150x150.jpg",150,150,true],"medium":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-300x188.jpg",300,188,true],"medium_large":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-768x480.jpg",768,480,true],"large":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg",800,500,false],"1536x1536":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg",800,500,false],"2048x2048":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg",800,500,false],"ashe-slider-grid-thumbnail":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-800x390.jpg",800,390,true],"ashe-full-thumbnail":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg",800,500,false],"ashe-grid-thumbnail":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-500x281.jpg",500,281,true],"ashe-list-thumbnail":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-300x300.jpg",300,300,true],"ashe-single-navigation":["https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation-75x75.jpg",75,75,true]},"post_excerpt_stackable_v2":"<p>Dans une pr\u00e9c\u00e9dente vid\u00e9o, nous avons appris a utiliser des mati\u00e8res, des mat\u00e9riaux pour amener des effets dans une aquarelle. Je propose la r\u00e9alisation d&rsquo;un paysage abstrait de mer, vagues et plage. Vous y utiliserez de la p\u00e2te granuleuse, du ruban de masquage, une carte plastique, du gel de masquage, une \u00e9ponge. Cette composition part d&rsquo;un paysage imaginaire o\u00f9 m&rsquo;on se trouve au bord de la mer avec les vagues qui d\u00e9ferlent et on regarde le lointain. Il apparait du relief de la quasi 3D dans le r\u00e9sultat assez int\u00e9ressant. Le tout est expliqu\u00e9 \u00e9tape par \u00e9tape comme toujours. Je\u2026<\/p>\n","category_list_v2":"<a href=\"https:\/\/creativ-ariane.fr\/index.php\/category\/aquarelle\/\" rel=\"category tag\">Aquarelle<\/a>","author_info_v2":{"name":"Creativ'Ariane","url":"https:\/\/creativ-ariane.fr\/index.php\/author\/admin6017\/"},"comments_num_v2":"0 commentaire","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Effets &amp; mati\u00e8re - Creativ&#039;Ariane<\/title>\n<meta name=\"description\" content=\"Une aquarelle abstraite d&#039;un paysage de mer utilisant des effets de mati\u00e8re avec une p\u00e2te granuleuse, et d&#039;autres effets.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Effets &amp; mati\u00e8re - Creativ&#039;Ariane\" \/>\n<meta property=\"og:description\" content=\"Une aquarelle abstraite d&#039;un paysage de mer utilisant des effets de mati\u00e8re avec une p\u00e2te granuleuse, et d&#039;autres effets.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/\" \/>\n<meta property=\"og:site_name\" content=\"Creativ&#039;Ariane\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-27T14:36:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-27T14:41:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Creativ&#039;Ariane\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Creativ&#039;Ariane\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/\"},\"author\":{\"name\":\"Creativ'Ariane\",\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/#\\\/schema\\\/person\\\/1befd623fcab198cb8ce79dca25545e4\"},\"headline\":\"Effets &#038; mati\u00e8re\",\"datePublished\":\"2023-05-27T14:36:09+00:00\",\"dateModified\":\"2023-05-27T14:41:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/#\\\/schema\\\/person\\\/1befd623fcab198cb8ce79dca25545e4\"},\"image\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/details-et-ombres-finalisation.jpg\",\"keywords\":[\"abstrait\",\"effets\"],\"articleSection\":[\"Aquarelle\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/\",\"url\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/\",\"name\":\"Effets & mati\u00e8re - Creativ&#039;Ariane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/details-et-ombres-finalisation.jpg\",\"datePublished\":\"2023-05-27T14:36:09+00:00\",\"dateModified\":\"2023-05-27T14:41:01+00:00\",\"description\":\"Une aquarelle abstraite d'un paysage de mer utilisant des effets de mati\u00e8re avec une p\u00e2te granuleuse, et d'autres effets.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/details-et-ombres-finalisation.jpg\",\"contentUrl\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/details-et-ombres-finalisation.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/index.php\\\/2023\\\/05\\\/27\\\/effets-matiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/creativ-ariane.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Effets &#038; mati\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/#website\",\"url\":\"https:\\\/\\\/creativ-ariane.fr\\\/\",\"name\":\"Creativ-Ariane\",\"description\":\"Des tutos dessin, aquarelle et scrapbooking et histoires des fleurs et voyages\",\"publisher\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/#\\\/schema\\\/person\\\/1befd623fcab198cb8ce79dca25545e4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/creativ-ariane.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/#\\\/schema\\\/person\\\/1befd623fcab198cb8ce79dca25545e4\",\"name\":\"Creativ'Ariane\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-logo-1-creativ-ariane-1.png\",\"url\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-logo-1-creativ-ariane-1.png\",\"contentUrl\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-logo-1-creativ-ariane-1.png\",\"width\":1496,\"height\":572,\"caption\":\"Creativ'Ariane\"},\"logo\":{\"@id\":\"https:\\\/\\\/creativ-ariane.fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-logo-1-creativ-ariane-1.png\"},\"description\":\"ARIANE, EDITRICE DE CONTENU De formation artistique et digitale, je vous emm\u00e8ne dans ma passion des histoires de fleurs et de voyage, mais aussi dans l\u2019art pour mieux les d\u00e9couvrir et apprendre \u00e0 les peindre.\",\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCfK82o7zAGaBsr2CnZsMA-w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Effets & mati\u00e8re - Creativ&#039;Ariane","description":"Une aquarelle abstraite d'un paysage de mer utilisant des effets de mati\u00e8re avec une p\u00e2te granuleuse, et d'autres effets.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/","og_locale":"fr_FR","og_type":"article","og_title":"Effets & mati\u00e8re - Creativ&#039;Ariane","og_description":"Une aquarelle abstraite d'un paysage de mer utilisant des effets de mati\u00e8re avec une p\u00e2te granuleuse, et d'autres effets.","og_url":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/","og_site_name":"Creativ&#039;Ariane","article_published_time":"2023-05-27T14:36:09+00:00","article_modified_time":"2023-05-27T14:41:01+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg","type":"image\/jpeg"}],"author":"Creativ'Ariane","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Creativ'Ariane","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/#article","isPartOf":{"@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/"},"author":{"name":"Creativ'Ariane","@id":"https:\/\/creativ-ariane.fr\/#\/schema\/person\/1befd623fcab198cb8ce79dca25545e4"},"headline":"Effets &#038; mati\u00e8re","datePublished":"2023-05-27T14:36:09+00:00","dateModified":"2023-05-27T14:41:01+00:00","mainEntityOfPage":{"@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/"},"wordCount":551,"publisher":{"@id":"https:\/\/creativ-ariane.fr\/#\/schema\/person\/1befd623fcab198cb8ce79dca25545e4"},"image":{"@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/#primaryimage"},"thumbnailUrl":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg","keywords":["abstrait","effets"],"articleSection":["Aquarelle"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/","url":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/","name":"Effets & mati\u00e8re - Creativ&#039;Ariane","isPartOf":{"@id":"https:\/\/creativ-ariane.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/#primaryimage"},"image":{"@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/#primaryimage"},"thumbnailUrl":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg","datePublished":"2023-05-27T14:36:09+00:00","dateModified":"2023-05-27T14:41:01+00:00","description":"Une aquarelle abstraite d'un paysage de mer utilisant des effets de mati\u00e8re avec une p\u00e2te granuleuse, et d'autres effets.","breadcrumb":{"@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/#primaryimage","url":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg","contentUrl":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/creativ-ariane.fr\/index.php\/2023\/05\/27\/effets-matiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/creativ-ariane.fr\/"},{"@type":"ListItem","position":2,"name":"Effets &#038; mati\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/creativ-ariane.fr\/#website","url":"https:\/\/creativ-ariane.fr\/","name":"Creativ-Ariane","description":"Des tutos dessin, aquarelle et scrapbooking et histoires des fleurs et voyages","publisher":{"@id":"https:\/\/creativ-ariane.fr\/#\/schema\/person\/1befd623fcab198cb8ce79dca25545e4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/creativ-ariane.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/creativ-ariane.fr\/#\/schema\/person\/1befd623fcab198cb8ce79dca25545e4","name":"Creativ'Ariane","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2020\/08\/cropped-logo-1-creativ-ariane-1.png","url":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2020\/08\/cropped-logo-1-creativ-ariane-1.png","contentUrl":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2020\/08\/cropped-logo-1-creativ-ariane-1.png","width":1496,"height":572,"caption":"Creativ'Ariane"},"logo":{"@id":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2020\/08\/cropped-logo-1-creativ-ariane-1.png"},"description":"ARIANE, EDITRICE DE CONTENU De formation artistique et digitale, je vous emm\u00e8ne dans ma passion des histoires de fleurs et de voyage, mais aussi dans l\u2019art pour mieux les d\u00e9couvrir et apprendre \u00e0 les peindre.","sameAs":["https:\/\/www.youtube.com\/channel\/UCfK82o7zAGaBsr2CnZsMA-w"]}]}},"jetpack_featured_media_url":"https:\/\/creativ-ariane.fr\/wp-content\/uploads\/2023\/05\/details-et-ombres-finalisation.jpg","acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/posts\/3361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3361"}],"version-history":[{"count":10,"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/posts\/3361\/revisions"}],"predecessor-version":[{"id":3387,"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/posts\/3361\/revisions\/3387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/media\/3362"}],"wp:attachment":[{"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/creativ-ariane.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}